{"id":6753,"date":"2026-02-18T11:06:48","date_gmt":"2026-02-18T10:06:48","guid":{"rendered":"https:\/\/carpinteriajlpascual.com\/\/home\/"},"modified":"2026-05-12T10:25:59","modified_gmt":"2026-05-12T08:25:59","slug":"home","status":"publish","type":"page","link":"https:\/\/carpinteriajlpascual.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#d1d1ca&#8221; bg_image=&#8221;6176&#8243; bg_image_phone=&#8221;14686&#8243; background_image_preload=&#8221;true&#8221; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;lazy-load&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;350&#8243; bg_image_animation=&#8221;zoom-out&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium_fast&#8221; shape_type=&#8221;mountains&#8221; gradient_type=&#8221;default&#8221; height_desktop=&#8221;90vh&#8221; height_phone=&#8221;95vh&#8221; height_tablet=&#8221;70vh&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1771429532908{margin-bottom: 10px !important;padding-right: 20px !important;padding-left: 20px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h1&#8243; fit_text_to_container=&#8221;true&#8221; content_alignment=&#8221;center&#8221; mobile_content_alignment=&#8221;center&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Aluminium and PVC joinery in Cocentaina and J\u00e1vea&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1.2&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1771412308062{border-top-width: 1px !important;border-top-style: solid !important;border-color: #FFFFFF8C !important;}&#8221;][vc_column_inner top_padding_desktop=&#8221;3%&#8221; bottom_padding_desktop=&#8221;6%&#8221; left_padding_desktop=&#8221;30px&#8221; right_padding_desktop=&#8221;30px&#8221; bottom_padding_tablet=&#8221;3%&#8221; left_padding_tablet=&#8221;30px&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;30px&#8221; bottom_padding_phone=&#8221;3%&#8221; left_padding_phone=&#8221;20px&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;20px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;banner-column&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;h2&#8243; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;30px&#8221; font_line_height=&#8221;1.2&#8243; max_width=&#8221;500&#8243;]Windows, home automation &amp; enclosures in J\u00e1vea[\/nectar_responsive_text][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8221;3%&#8221; bottom_padding_desktop=&#8221;6%&#8221; left_padding_desktop=&#8221;30px&#8221; right_padding_desktop=&#8221;30px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1px&#8221; border_top_tablet=&#8221;1px&#8221; border_top_phone=&#8221;1px&#8221; column_border_color=&#8221;#FFFFFF8C&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;p&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;16px&#8221; font_line_height=&#8221;20px&#8221;]At <strong>Carpinter\u00eda JL Pascual<\/strong>, we specialise in<strong> aluminium and PVC joinery<\/strong> for high-end homes, villas, renovations and new-build projects in <strong>Cocentaina <\/strong>and <strong>J\u00e1vea<\/strong>, with more than 15 years of experience.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column left_padding_desktop=&#8221;20%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;20%&#8221; left_padding_tablet=&#8221;5%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;5%&#8221; left_padding_phone=&#8221;3%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;3%&#8221; flex_gap_desktop=&#8221;10px&#8221; desktop_text_alignment=&#8221;left&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;flexbox&#8221; gradient_type=&#8221;default&#8221; flex_layout_desktop=&#8221;column&#8221; flex_layout_phone=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_justify_content_phone=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;30px&#8221; font_line_height=&#8221;1.2&#8243; font_size_phone=&#8221;20px&#8221;]We design, manufacture and install <strong>bespoke windows<\/strong>, <strong>entrance doors<\/strong>, <strong>exterior enclosures<\/strong> and <strong>glass solutions <\/strong>for refined residential projects.[\/nectar_responsive_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;left&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Carpinteria JL Pascual&#8221; url=&#8221;https:\/\/carpinteriajlpascual.com\/\/en\/company\/&#8221; aria_label_text=&#8221;Carpinteria JL Pascual&#8221; font_size_desktop=&#8221;16px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;70px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column left_padding_desktop=&#8221;30%&#8221; left_padding_tablet=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; constrain_group_5=&#8221;yes&#8221; left_margin_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_margin_phone=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;image-column&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out-reveal&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;0&#8243; constrain_group_1=&#8221;yes&#8221; bottom_margin=&#8221;0&#8243; left_margin=&#8221;0&#8243; constrain_group_2=&#8221;yes&#8221; right_margin=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;6174&#8243; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;front&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;lazy-load&#8221; column_backdrop_filter=&#8221;blur&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;reveal-from-right&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out-high&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;500&#8243; custom_height_phone=&#8221;300&#8243; custom_height_tablet=&#8221;400&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column top_padding_desktop=&#8221;2%&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;2%&#8221; flex_justify_content_tablet=&#8221;flex-start&#8221; flex_align_items_tablet=&#8221;flex-start&#8221; flex_gap_desktop=&#8221;20px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;flexbox&#8221; gradient_type=&#8221;default&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;center&#8221; flex_justify_content_phone=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1771424770716{margin-bottom: 15px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_justify_content_tablet=&#8221;flex-start&#8221; flex_align_items_tablet=&#8221;flex-start&#8221; flex_gap_desktop=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;column-reverse&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;true&#8221; gradient_type=&#8221;default&#8221; flex_justify_content_phone=&#8221;flex-start&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Professional supply and installation&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;550&#8243; el_class=&#8221;none-margin-title&#8221; font_line_height=&#8221;1.1&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h3&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;What do we do?&#8221; max_width=&#8221;450&#8243; text_direction=&#8221;default&#8221; font_size=&#8221;20px&#8221; font_line_height=&#8221;1.2&#8243; el_class=&#8221;subtitle&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;.vc_custom_1778497463319{margin-bottom: 0px !important;}&#8221; max_width=&#8221;500&#8243; text_direction=&#8221;default&#8221;]Exterior aluminium and PVC joinery in Cocentaina and J\u00e1vea.<br \/>\nWe work for clients who expect flawless finishes, expert guidance and carefully managed service for villas and renovations.[\/vc_column_text][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;default&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221; custom_height=&#8221;10&#8243; custom_line_width=&#8221;80&#8243;][vc_column_text css=&#8221;.vc_custom_1778497069923{margin-top: 0px !important;margin-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;500&#8243;]Our head office and one showroom are in <strong>Cocentaina<\/strong>. We also have a showroom in <strong>J\u00e1vea<\/strong>, where you can see, touch and compare our solutions.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;productos&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1771426357952{margin-bottom: 10px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;category-heading&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Products&#8221; text_direction=&#8221;default&#8221; font_size_phone=&#8221;30px&#8221; font_line_height=&#8221;1&#8243; el_class=&#8221;none-margin-title&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_justify_content_tablet=&#8221;flex-start&#8221; flex_align_items_tablet=&#8221;flex-start&#8221; flex_gap_desktop=&#8221;15px&#8221; flex_gap_tablet=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;category-class-column&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;9\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;row&#8221; flex_justify_content_desktop=&#8221;flex-end&#8221; flex_align_items_desktop=&#8221;flex-end&#8221; flex_align_items_phone=&#8221;center&#8221; flex_wrap_desktop=&#8221;wrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221; flex_layout_phone=&#8221;column&#8221; flex_wrap_phone=&#8221;wrap&#8221; flex_justify_content_phone=&#8221;center&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][nectar_cta btn_style=&#8221;underline&#8221; underline_visibility=&#8221;visible-on-hover&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;center&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Finstral and Technal windows&#8221; font_size_desktop=&#8221;14px&#8221; url=&#8221;\/en\/windows-and-doors\/bespoke-windows\/&#8221;][nectar_cta btn_style=&#8221;underline&#8221; underline_visibility=&#8221;visible-on-hover&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;center&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Entrance doors&#8221; font_size_desktop=&#8221;14px&#8221; url=&#8221;\/en\/windows-and-doors\/entrance-doors\/&#8221;][nectar_cta btn_style=&#8221;underline&#8221; underline_visibility=&#8221;visible-on-hover&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;center&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Terrace enclosures&#8221; font_size_desktop=&#8221;14px&#8221; url=&#8221;\/en\/windows-and-doors\/exterior-enclosures\/&#8221;][nectar_cta btn_style=&#8221;underline&#8221; underline_visibility=&#8221;visible-on-hover&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;center&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Bioclimatic pergolas&#8221; font_size_desktop=&#8221;14px&#8221; url=&#8221;\/en\/windows-and-doors\/glass-balustrades-and-other-elements\/&#8221;][nectar_cta btn_style=&#8221;underline&#8221; underline_visibility=&#8221;visible-on-hover&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;center&#8221; alignment_phone=&#8221;center&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Garage doors&#8221; font_size_desktop=&#8221;14px&#8221; url=&#8221;\/en\/windows-and-doors\/entrance-doors\/&#8221;][nectar_cta btn_style=&#8221;underline&#8221; underline_visibility=&#8221;visible-on-hover&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;center&#8221; alignment_phone=&#8221;center&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Home automation for doors, blinds and shutters&#8221; font_size_desktop=&#8221;14px&#8221; url=&#8221;\/en\/windows-and-doors\/glass-balustrades-and-other-elements\/&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;15px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221; flex_justify_content_phone=&#8221;center&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][image_with_animation image_url=&#8221;6173&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-fade-top&#8221; font_style=&#8221;h3&#8243; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Windows&#8221; font_size=&#8221;20px&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; el_class=&#8221;b-text product-category product-category-title&#8221;][\/split_line_heading][vc_column_text css=&#8221;.vc_custom_1778497271999{margin-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221;]Bespoke windows in Cocentaina and J\u00e1vea, with thermal and acoustic insulation.[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;View Products&#8221; url=&#8221;\/en\/windows-and-doors\/bespoke-windows\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;15px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221; flex_justify_content_phone=&#8221;center&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][image_with_animation image_url=&#8221;6172&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; delay=&#8221;100&#8243;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-fade-top&#8221; font_style=&#8221;h3&#8243; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Doors&#8221; font_size=&#8221;20px&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; el_class=&#8221;b-text product-category product-category-title&#8221;][\/split_line_heading][vc_column_text css=&#8221;.vc_custom_1778497281239{margin-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221;]Secure, elegant and bespoke entrance doors.[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;View Products&#8221; url=&#8221;\/en\/windows-and-doors\/entrance-doors\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;15px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221; flex_justify_content_phone=&#8221;center&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][image_with_animation image_url=&#8221;6170&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; delay=&#8221;200&#8243;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-fade-top&#8221; font_style=&#8221;h3&#8243; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Exterior enclosures&#8221; font_size=&#8221;20px&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; el_class=&#8221;b-text product-category product-category-title&#8221;][\/split_line_heading][vc_column_text css=&#8221;.vc_custom_1778497290276{margin-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221;]Terrace enclosures in Cocentaina and J\u00e1vea to enjoy your home all year round.[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;View Products&#8221; url=&#8221;\/en\/windows-and-doors\/exterior-enclosures\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;15px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221; flex_justify_content_phone=&#8221;center&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][image_with_animation image_url=&#8221;6171&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; delay=&#8221;300&#8243;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-fade-top&#8221; font_style=&#8221;h3&#8243; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Other elements&#8221; font_size=&#8221;20px&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; el_class=&#8221;b-text product-category product-category-title&#8221;][\/split_line_heading][vc_column_text css=&#8221;.vc_custom_1778497306320{margin-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221;]Bioclimatic pergolas, glass balustrades, shower screens and glass solutions.[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;View Products&#8221; url=&#8221;\/en\/windows-and-doors\/glass-balustrades-and-other-elements\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;product-category-carousel&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;4&#8243; desktop_small_cols_flickity=&#8221;3&#8243; tablet_cols_flickity=&#8221;2&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;touch_total&#8221; flickity_touch_total_style=&#8221;default&#8221; flickity_touch_total_hide_indicator=&#8221;true&#8221; flickity_touch_total_icon_color=&#8221;default&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_spacing=&#8221;5px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;default&#8221; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_justify_content_tablet=&#8221;flex-start&#8221; flex_align_items_tablet=&#8221;flex-start&#8221; flex_gap_desktop=&#8221;15px&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1778573799797-3&#8243; tab_id=&#8221;1778573799797-4&#8243; title=&#8221;Elemento&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_justify_content_phone=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][image_with_animation image_url=&#8221;6173&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-fade-top&#8221; font_style=&#8221;p&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Windows&#8221; font_size=&#8221;20px&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; el_class=&#8221;b-text product-category product-category-title&#8221;][\/split_line_heading][vc_column_text css=&#8221;.vc_custom_1778497321814{margin-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221;]Bespoke windows in Cocentaina and J\u00e1vea, with thermal and acoustic insulation.[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;View Products&#8221; url=&#8221;\/en\/windows-and-doors\/bespoke-windows\/&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_justify_content_tablet=&#8221;flex-start&#8221; flex_align_items_tablet=&#8221;flex-start&#8221; flex_gap_desktop=&#8221;15px&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1778573799870-3&#8243; tab_id=&#8221;1778573799871-9&#8243; title=&#8221;Elemento&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_justify_content_phone=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][image_with_animation image_url=&#8221;6172&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; delay=&#8221;100&#8243;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-fade-top&#8221; font_style=&#8221;p&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Doors&#8221; font_size=&#8221;20px&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; el_class=&#8221;b-text product-category product-category-title&#8221;][\/split_line_heading][vc_column_text css=&#8221;.vc_custom_1778497334901{margin-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221;]Secure, elegant and bespoke entrance doors.[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;View Products&#8221; url=&#8221;\/en\/windows-and-doors\/entrance-doors\/&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_justify_content_tablet=&#8221;flex-start&#8221; flex_align_items_tablet=&#8221;flex-start&#8221; flex_gap_desktop=&#8221;15px&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1778573799938-1&#8243; tab_id=&#8221;1778573799939-2&#8243; title=&#8221;Elemento&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_justify_content_phone=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][image_with_animation image_url=&#8221;6170&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; delay=&#8221;200&#8243;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-fade-top&#8221; font_style=&#8221;p&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Exterior enclosures&#8221; font_size=&#8221;20px&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; el_class=&#8221;b-text product-category product-category-title&#8221;][\/split_line_heading][vc_column_text css=&#8221;.vc_custom_1778497345027{margin-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221;]Terrace enclosures in Cocentaina and J\u00e1vea to enjoy your home all year round.[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;View Products&#8221; url=&#8221;\/en\/windows-and-doors\/exterior-enclosures\/&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_justify_content_tablet=&#8221;flex-start&#8221; flex_align_items_tablet=&#8221;flex-start&#8221; flex_gap_desktop=&#8221;15px&#8221; flickity_item_link_type=&#8221;regular&#8221; title=&#8221;Elemento&#8221; id=&#8221;1778573800018-8&#8243; tab_id=&#8221;1778573800019-7&#8243; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_justify_content_phone=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;flex-start&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][image_with_animation image_url=&#8221;6171&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; delay=&#8221;300&#8243;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-fade-top&#8221; font_style=&#8221;p&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Other elements&#8221; font_size=&#8221;20px&#8221; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; el_class=&#8221;b-text product-category product-category-title&#8221;][\/split_line_heading][vc_column_text css=&#8221;.vc_custom_1778497355624{margin-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221;]Bioclimatic pergolas, glass balustrades, shower screens and glass solutions.[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;View Products&#8221; url=&#8221;\/en\/windows-and-doors\/glass-balustrades-and-other-elements\/&#8221;][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_phone=&#8221;20%&#8221; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Products designed for projects that require insulation, security, design, durability and professional installation.&#8221; text_direction=&#8221;default&#8221; font_size=&#8221;30px&#8221; font_line_height=&#8221;1.2&#8243; el_class=&#8221;b-text&#8221; font_size_phone=&#8221;20px&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;16px&#8221; font_line_height=&#8221;20px&#8221; class_name=&#8221;justified-responsive&#8221;]We work with <strong>Finstral and Technal windows<\/strong>, international references in energy efficiency, design and comfort for <strong>coastal projects<\/strong> and clients who value the <strong>highest quality<\/strong>. We also offer windows with Passivhaus certification, suitable for projects seeking a high level of thermal and acoustic insulation within a personalised, well-installed solution.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; flex_justify_content_tablet=&#8221;center&#8221; flex_align_items_tablet=&#8221;center&#8221; flex_gap_desktop=&#8221;10px&#8221; flex_gap_phone=&#8221;20px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;brand-column&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;row&#8221; flex_justify_content_desktop=&#8221;space-between&#8221; flex_align_items_desktop=&#8221;center&#8221; flex_align_items_phone=&#8221;center&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221; flex_justify_content_phone=&#8221;center&#8221; flex_layout_phone=&#8221;column&#8221; flex_wrap_phone=&#8221;nowrap&#8221; flex_wrap_tablet=&#8221;nowrap&#8221;][image_with_animation image_url=&#8221;6165&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; el_class=&#8221;brand-logo&#8221; img_link=&#8221;https:\/\/www.finstral.com\/es\/home\/1-0.html&#8221;][image_with_animation image_url=&#8221;6169&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.technal.com\/es-es\/profesionales&#8221; el_class=&#8221;brand-logo&#8221;][image_with_animation image_url=&#8221;6163&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/alumedsistemas.com\/&#8221; el_class=&#8221;brand-logo&#8221;][image_with_animation image_url=&#8221;6167&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.pirnar.es\/&#8221; el_class=&#8221;brand-logo&#8221;][image_with_animation image_url=&#8221;6166&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/www.nfi.pt\/&#8221; el_class=&#8221;brand-logo&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;0&#8243; bottom_padding_tablet=&#8221;0&#8243; bottom_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;center&#8221; mobile_content_alignment=&#8221;center&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;700&#8243; text_content=&#8221;Design, efficiency and quality for coastal projects&#8221;]\n<p style=\"text-align: center;\">The most demanding standards of efficiency and quality.<\/p>\n[\/split_line_heading][vc_gallery css=&#8221;.vc_custom_1772466709143{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221; type=&#8221;flickity_static_height_style&#8221; images=&#8221;6741,6742,6743,6744,6745,6746,6747,6748,6749,6750,6751,6752&#8243; flickity_spacing=&#8221;5px&#8221; flickity_controls=&#8221;next_prev_arrows_overlaid&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_image_parallax=&#8221;true&#8221; flickity_box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;lazy-load&#8221; onclick=&#8221;link_image&#8221; flickity_img_height=&#8221;450&#8243; el_class=&#8221;image-carousel&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;blog-column&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;8\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1772467306354{margin-bottom: 0px !important;}&#8221;][vc_column_inner bottom_padding_desktop=&#8221;3%&#8221; bottom_padding_phone=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;center&#8221; mobile_content_alignment=&#8221;center&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Updates on windows, doors and enclosures&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;700&#8243; el_class=&#8221;mobile-centered-text&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][recent_posts style=&#8221;list_featured_first_row_tall&#8221; columns=&#8221;3&#8243; category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; image_loading=&#8221;lazy-load&#8221; blog_remove_post_author=&#8221;true&#8221; blog_remove_post_comment_number=&#8221;true&#8221; posts_per_page=&#8221;3&#8243;][nectar_cta btn_style=&#8221;underline&#8221; underline_visibility=&#8221;default&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;See more news&#8221; url=&#8221;https:\/\/carpinteriajlpascual.com\/\/en\/news\/&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#d1d1ca&#8221; bg_image=&#8221;6176&#8243; bg_image_phone=&#8221;14686&#8243; background_image_preload=&#8221;true&#8221; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;lazy-load&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-6753","page","type-page","status-publish"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/carpinteriajlpascual.com\/en\/wp-json\/wp\/v2\/pages\/6753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carpinteriajlpascual.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/carpinteriajlpascual.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/carpinteriajlpascual.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carpinteriajlpascual.com\/en\/wp-json\/wp\/v2\/comments?post=6753"}],"version-history":[{"count":82,"href":"https:\/\/carpinteriajlpascual.com\/en\/wp-json\/wp\/v2\/pages\/6753\/revisions"}],"predecessor-version":[{"id":15392,"href":"https:\/\/carpinteriajlpascual.com\/en\/wp-json\/wp\/v2\/pages\/6753\/revisions\/15392"}],"wp:attachment":[{"href":"https:\/\/carpinteriajlpascual.com\/en\/wp-json\/wp\/v2\/media?parent=6753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}